{"id":4977,"date":"2024-04-21T20:41:07","date_gmt":"2024-04-21T20:41:07","guid":{"rendered":"https:\/\/bicentenariosantamaria.cl\/?p=4977"},"modified":"2024-09-23T14:10:27","modified_gmt":"2024-09-23T14:10:27","slug":"nuestros-estudiantes-obtuvieron-el-tercer-lugar-en-la-copa-scotia-bank","status":"publish","type":"post","link":"https:\/\/bicentenariosantamaria.cl\/index.php\/2024\/04\/21\/nuestros-estudiantes-obtuvieron-el-tercer-lugar-en-la-copa-scotia-bank\/","title":{"rendered":""},"content":{"rendered":"\n<p class=\"has-base-3-color has-luminous-vivid-orange-background-color has-text-color has-background\" style=\"font-size:25px\"><strong>Nuestros estudiantes obtuvieron el tercer lugar en la Copa Scotia&nbsp;Bank<\/strong><\/p>\n\n\n\n\n\n\n\n<p>Nuestro equipo obtuvo el tercer puesto en la Copa Scotiabank, nivel de equipos mixtos nacidos en los a\u00f1os\u00a02013\u00a0y\u00a02014. Actividad donde participaron 48 colegios tanto p\u00fablicos como privados de la Region Metropolitana. El Campeonato de llev\u00f3 a cabo en las canchas del Club Deportivo Universidad Cat\u00f3lica en San Carlos de Apoquindo. La competencia fue organizada por el banco Scotia Bank.<\/p>\n\n\n\n<p>Felicitamos al equipo conformado por: Florencia Castillo, Antonella Aguilera, Isidora Rivera (4\u00b0 b\u00e1sico A), Emma Becerra (5\u00b0 b\u00e1sico A), Gabriel Parra, M\u00e1ximo Quintanilla (5\u00b0 b\u00e1sico B), Adri\u00e1n M\u00e1rquez y Sebasti\u00e1n Medina (6\u00b0 b\u00e1sico B). Y a su profesor a cargo don Carlos Marambio por su gran logro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros estudiantes obtuvieron el tercer lugar en la Copa Scotia&nbsp;Bank Nuestro equipo obtuvo el tercer puesto en la Copa Scotiabank, nivel de equipos mixtos nacidos en los a\u00f1os\u00a02013\u00a0y\u00a02014. Actividad donde participaron 48 colegios tanto p\u00fablicos como privados de la Region Metropolitana. El Campeonato de llev\u00f3 a cabo en las canchas del Club Deportivo Universidad Cat\u00f3lica &#8230; <a title=\"\" class=\"read-more\" href=\"https:\/\/bicentenariosantamaria.cl\/index.php\/2024\/04\/21\/nuestros-estudiantes-obtuvieron-el-tercer-lugar-en-la-copa-scotia-bank\/\" aria-label=\"Leer m\u00e1s sobre \">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[1],"tags":[257],"class_list":["post-4977","post","type-post","status-publish","format-standard","hentry","category-portada","tag-nuestros-estudiantes-obtuvieron-el-tercer-lugar-en-la-copa-scotia-bank"],"_links":{"self":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/posts\/4977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4977"}],"version-history":[{"count":0,"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/posts\/4977\/revisions"}],"wp:attachment":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}