{"id":136,"count":1,"description":"","link":"https:\/\/bicentenariosantamaria.cl\/index.php\/tag\/nuestro-dirigente-del-centro-de-alumnos-don-santiago-estrada-se-destaca-con-proyecto-de-accion-comunal\/","name":"Nuestro dirigente del centro de Alumnos Don Santiago Estrada se destaca con proyecto de acci\u00f3n comunal","slug":"nuestro-dirigente-del-centro-de-alumnos-don-santiago-estrada-se-destaca-con-proyecto-de-accion-comunal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/tags\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bicentenariosantamaria.cl\/index.php\/wp-json\/wp\/v2\/posts?tags=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}